{"id":1325,"date":"2024-12-13T15:30:28","date_gmt":"2024-12-13T15:30:28","guid":{"rendered":"https:\/\/davidsinsurance2.com\/?page_id=1325"},"modified":"2025-10-23T15:21:52","modified_gmt":"2025-10-23T15:21:52","slug":"contacto-3","status":"publish","type":"page","link":"https:\/\/davidsinsurance2.com\/en\/contacto-3\/","title":{"rendered":"Contact"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1325\" class=\"elementor elementor-1325\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48dfbdd elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"48dfbdd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6057b3c\" data-id=\"6057b3c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6d9f468 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d9f468\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-09594a0\" data-id=\"09594a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-464f8a4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"464f8a4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Contact<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57374a7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"57374a7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5d7f23c\" data-id=\"5d7f23c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cafea28 elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"cafea28\" data-element_type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/davidsinsurance2.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Animation-1735531894617.json&quot;,&quot;id&quot;:1358,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;loop&quot;:&quot;yes&quot;,&quot;reverse_animation&quot;:&quot;yes&quot;,&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df9c981 elementor-widget elementor-widget-heading\" data-id=\"df9c981\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schedule<br>Lunes a viernes\n10:30 a.m a 7:00 p.m.<br>Sabados 10:30 am a  5:00 p.m<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-31e7f74\" data-id=\"31e7f74\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7755732 elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"7755732\" data-element_type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/davidsinsurance2.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Animation-1735532020869.json&quot;,&quot;id&quot;:1361,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;loop&quot;:&quot;yes&quot;,&quot;reverse_animation&quot;:&quot;yes&quot;,&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e986323 elementor-widget elementor-widget-heading\" data-id=\"e986323\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:+17707748913\">Call us<br>\n770 774 8913<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9b144ee\" data-id=\"9b144ee\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa706d8 elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"aa706d8\" data-element_type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/davidsinsurance2.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Animation-1735531817192.json&quot;,&quot;id&quot;:1359,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;loop&quot;:&quot;yes&quot;,&quot;reverse_animation&quot;:&quot;yes&quot;,&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2a1be6 elementor-widget elementor-widget-heading\" data-id=\"b2a1be6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.google.com\/maps\/place\/El+Amigo+Supermarket\/@33.565682,-84.5837627,19z\/data=!4m6!3m5!1s0x88f4e7157c422b37:0x99891d4f4dc428ef!8m2!3d33.5655883!4d-84.5833483!16s%2Fg%2F1tf71s8j?hl=es&#038;entry=ttu\" target=\"_blank\">Fairburn:  13 Smith St, Fairburn, GA 30213\n<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9e65a37\" data-id=\"9e65a37\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eac6f5d elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"eac6f5d\" data-element_type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/davidsinsurance2.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Animation-1735531817192.json&quot;,&quot;id&quot;:1359,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;loop&quot;:&quot;yes&quot;,&quot;reverse_animation&quot;:&quot;yes&quot;,&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7943ab1 elementor-widget elementor-widget-heading\" data-id=\"7943ab1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.google.com\/maps\/place\/150+Strickland+Rd,+Alpharetta,+GA+30004,+EE.+UU.\/@34.1273633,-84.2572714,17z\/data=!4m6!3m5!1s0x88f59dec85a73211:0xa1dffc702b1f2bce!8m2!3d34.1280995!4d-84.2547581!16s%2Fg%2F11bw4pgfd3?entry=ttu\" target=\"_blank\">Alpharetta:150 Strickland Rd , Alpharetta, GA 30004<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-34308df\" data-id=\"34308df\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12df083 elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"12df083\" data-element_type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/davidsinsurance2.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Animation-1735531817192.json&quot;,&quot;id&quot;:1359,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;loop&quot;:&quot;yes&quot;,&quot;reverse_animation&quot;:&quot;yes&quot;,&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b1c6db elementor-widget elementor-widget-heading\" data-id=\"5b1c6db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.google.com\/maps\/place\/10479+Alpharetta+St,+Roswell,+GA+30075,+EE.+UU.\/@34.0339931,-84.3481006,17z\/data=!3m1!4b1!4m5!3m4!1s0x88f574af89467701:0xefe5f9aad15b877d!8m2!3d34.0339887!4d-84.3459066\" target=\"_blank\">Roswell: 10479 Alpharetta Street Suite #2, Roswell, GA 30075<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cd37ff5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cd37ff5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64dd9350\" data-id=\"64dd9350\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b601af elementor-widget elementor-widget-osm-map-elementor\" data-id=\"8b601af\" data-element_type=\"widget\" data-widget_type=\"osm-map-elementor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"osm-map-8b601af\" \n        class=\"osm-map-container\" \n        data-center=\"33.901801429376,-84.414072817752\"><\/div>        <script type=\"text\/javascript\">\n                    <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6b384ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b384ce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-22f8129\" data-id=\"22f8129\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e70cf74\" data-id=\"5e70cf74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d853623 elementor-widget__width-auto animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4d853623\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Leave us your details and we will get in contact\nas soon as possible.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02e3496 elementor-widget elementor-widget-shortcode\" data-id=\"02e3496\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class='fluentform ff-default fluentform_wrapper_1 ffs_default_wrap'><form data-form_id=\"1\" id=\"fluentform_1\" class=\"frm-fluent-form fluent_form_1 ff-el-form-top ff_form_instance_1_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_1_1\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Contact Form Demo<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='1325' \/><input type=\"hidden\" id=\"_fluentform_1_fluentformnonce\" name=\"_fluentform_1_fluentformnonce\" value=\"f8a15d7b2d\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/1325\" \/><div data-type=\"name-element\" data-name=\"names\" class=\"ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group  ff-el-form-left'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_names_first_name_' id='label_ff_1_names_first_name_' >Nombres<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_1_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Nombres\" aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><div class='ff-t-cell'><div class='ff-el-group  ff-el-form-left'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_names_last_name_' id='label_ff_1_names_last_name_' >Apellidos<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_1_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Apellidos\" aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_3'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 33.33%;'><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_email' id='label_ff_1_email' aria-label=\"Direction\">Direction<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_1_email\" class=\"ff-el-form-control\" placeholder=\"Calle - Ciudad - Estado\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 33.33%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_dropdown' id='label_ff_1_dropdown' aria-label=\"State\">State<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown\" id=\"ff_1_dropdown\" class=\"ff-el-form-control\" data-name=\"dropdown\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"false\" aria-labelledby=\"label_ff_1_dropdown\"><option value=\"\">- Seleccionar -<\/option><option value=\"Alabama\"  >Alabama<\/option><option value=\"Alaska\"  >Alaska<\/option><option value=\"Arizona\"  >Arizona<\/option><option value=\"Arkansas\"  >Arkansas<\/option><option value=\"California\"  >California<\/option><option value=\"Carolina del norte\"  >Carolina del norte<\/option><option value=\"Carolina del sur\"  >Carolina del sur<\/option><option value=\"Colorado\"  >Colorado<\/option><option value=\"Connecticut\"  >Connecticut<\/option><option value=\"Dakota del norte\"  >Dakota del norte<\/option><option value=\"Dakota del sur\"  >Dakota del sur<\/option><option value=\"Delaware\"  >Delaware<\/option><option value=\"Florida\"  >Florida<\/option><option value=\"Georgia\"  >Georgia<\/option><option value=\"Haw\u00e1i\"  >Haw\u00e1i<\/option><option value=\"Idaho\"  >Idaho<\/option><option value=\"Illinois\"  >Illinois<\/option><option value=\"Indiana\"  >Indiana<\/option><option value=\"Lowa\"  >Lowa<\/option><option value=\"Kansas\"  >Kansas<\/option><option value=\"Kentucky\"  >Kentucky<\/option><option value=\"Luisiana\"  >Luisiana<\/option><option value=\"Maine\"  >Maine<\/option><option value=\"Maryland\"  >Maryland<\/option><option value=\"Massachusetts\"  >Massachusetts<\/option><option value=\"M\u00edchigan\"  >M\u00edchigan<\/option><option value=\"Minesota\"  >Minesota<\/option><option value=\"Misisipi\"  >Misisipi<\/option><option value=\"Misuri\"  >Misuri<\/option><option value=\"Montana\"  >Montana<\/option><option value=\"Nebraska\"  >Nebraska<\/option><option value=\"Nevada\"  >Nevada<\/option><option value=\"Nueva jersey\"  >Nueva jersey<\/option><option value=\"Nueva york\"  >Nueva york<\/option><option value=\"Nuevo hampshire\"  >Nuevo hampshire<\/option><option value=\"Nuevo m\u00e9xico\"  >Nuevo m\u00e9xico<\/option><option value=\"Ohio\"  >Ohio<\/option><option value=\"Oklahoma\"  >Oklahoma<\/option><option value=\"Oreg\u00f3n\"  >Oreg\u00f3n<\/option><option value=\"Pensilvania\"  >Pensilvania<\/option><option value=\"Rhode island\"  >Rhode island<\/option><option value=\"Tennesse\"  >Tennesse<\/option><option value=\"Texas\"  >Texas<\/option><option value=\"Utha\"  >Utha<\/option><option value=\"Vermont\"  >Vermont<\/option><option value=\"Virginia\"  >Virginia<\/option><option value=\"Virginia occidental\"  >Virginia occidental<\/option><option value=\"Washington\"  >Washington<\/option><option value=\"Wisconsin\"  >Wisconsin<\/option><option value=\"Wyoming\"  >Wyoming<\/option><\/select><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-3' style='flex-basis: 33.33%;'><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_email_3' id='label_ff_1_email_3' aria-label=\"C\u00f3digo postal\">C\u00f3digo postal<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email_3\" id=\"ff_1_email_3\" class=\"ff-el-form-control\" placeholder=\"C\u00f3digo postal\" data-name=\"email_3\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_2\"  class='ff-t-container ff-column-container ff_columns_total_3'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 33.33%;'><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_email_4' id='label_ff_1_email_4' aria-label=\"Email\">Email<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email_4\" id=\"ff_1_email_4\" class=\"ff-el-form-control\" placeholder=\"Email \" data-name=\"email_4\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 33.33%;'><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_subject' id='label_ff_1_subject' aria-label=\"Phone\">Phone<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"subject\" class=\"ff-el-form-control\" placeholder=\"Phone\" data-name=\"subject\" id=\"ff_1_subject\"  aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-3' style='flex-basis: 33.33%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_input_text' id='label_ff_1_input_text' aria-label=\"Birthdate\">Birthdate<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" data-name=\"input_text\" id=\"ff_1_input_text\"  aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_3\"  class='ff-t-container ff-column-container ff_columns_total_4'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 25%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_dropdown_1' id='label_ff_1_dropdown_1' aria-label=\"Estado civil\">Estado civil<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown_1\" id=\"ff_1_dropdown_1\" class=\"ff-el-form-control\" data-name=\"dropdown_1\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"false\" aria-labelledby=\"label_ff_1_dropdown_1\"><option value=\"\">- Seleccionar -<\/option><option value=\"Casado\"  >Married<\/option><option value=\"Soltero\"  >Single<\/option><option value=\"Separado\"  >Separated<\/option><option value=\"Viudo\"  >Widower<\/option><\/select><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 25%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_dropdown_2' id='label_ff_1_dropdown_2' aria-label=\"ID Type\">ID Type<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown_2\" id=\"ff_1_dropdown_2\" class=\"ff-el-form-control\" data-name=\"dropdown_2\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"false\" aria-labelledby=\"label_ff_1_dropdown_2\"><option value=\"\">- Seleccionar -<\/option><option value=\"Licencia de conducir\"  >Licencia de conducir<\/option><option value=\"Licencia internacional\"  >Licencia internacional<\/option><option value=\"Pasaporte\"  >Passport<\/option><option value=\"Matricula consular\"  >Consular registration<\/option><\/select><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-3' style='flex-basis: 25%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_input_text_2' id='label_ff_1_input_text_2' aria-label=\"Identification number\">Identification number<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_2\" class=\"ff-el-form-control\" data-name=\"input_text_2\" id=\"ff_1_input_text_2\"  aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-4' style='flex-basis: 25%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_input_text_1' id='label_ff_1_input_text_1' aria-label=\"Country of origin of the document\">Country of origin of the document<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_1\" class=\"ff-el-form-control\" data-name=\"input_text_1\" id=\"ff_1_input_text_1\"  aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_4\"  class='ff-t-container ff-column-container ff_columns_total_4'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 25%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_input_text_3' id='label_ff_1_input_text_3' aria-label=\"Brand\">Brand<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_3\" class=\"ff-el-form-control\" data-name=\"input_text_3\" id=\"ff_1_input_text_3\"  aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 25%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_input_text_6' id='label_ff_1_input_text_6' aria-label=\"Year\">Year<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_6\" class=\"ff-el-form-control\" data-name=\"input_text_6\" id=\"ff_1_input_text_6\"  aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-3' style='flex-basis: 25%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_input_text_5' id='label_ff_1_input_text_5' aria-label=\"Model\">Model<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_5\" class=\"ff-el-form-control\" data-name=\"input_text_5\" id=\"ff_1_input_text_5\"  aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-4' style='flex-basis: 25%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_input_text_4' id='label_ff_1_input_text_4' aria-label=\"#VIN\">#VIN<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_4\" class=\"ff-el-form-control\" data-name=\"input_text_4\" id=\"ff_1_input_text_4\"  aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_5\"  class='ff-t-container ff-column-container ff_columns_total_2'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_dropdown_3' id='label_ff_1_dropdown_3' aria-label=\"Insurance data\">Insurance data<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown_3\" id=\"ff_1_dropdown_3\" class=\"ff-el-form-control\" data-name=\"dropdown_3\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"false\" aria-labelledby=\"label_ff_1_dropdown_3\"><option value=\"\">- Seleccionar -<\/option><option value=\"Cobertura\"  >Coverage<\/option><option value=\"Liability\"  >Liability<\/option><option value=\"Uninsured motorist\"  >Uninsured motorist<\/option><option value=\"Comp and collision\"  >Comp and collision<\/option><\/select><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"Additional coverage\">Additional coverage<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_2e321a53b90703b2d1a8b6d496767334'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Pagos m\u00e9dicos\"  id='checkbox_2e321a53b90703b2d1a8b6d496767334' aria-label='Medical payments' aria-invalid='false' aria-required=\"false\"> <span>Medical payments<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_185c0eb84d202456c35e55d94388acc1'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Reembolso por alquiler\"  id='checkbox_185c0eb84d202456c35e55d94388acc1' aria-label='Rental reimbursement:' aria-invalid='false' aria-required=\"false\"> <span>Rental reimbursement:<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_5af7668e1aba33eeaf773626cb97a129'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Asistencia en carretera\"  id='checkbox_5af7668e1aba33eeaf773626cb97a129' aria-label='Roadside assistance' aria-invalid='false' aria-required=\"false\"> <span>Roadside assistance<\/span><\/label><\/div><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_6\"  class='ff-t-container ff-column-container ff_columns_total_2'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_dropdown_4' id='label_ff_1_dropdown_4' aria-label=\"Aseguranza anterior\">Aseguranza anterior<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown_4\" id=\"ff_1_dropdown_4\" class=\"ff-el-form-control\" data-name=\"dropdown_4\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"false\" aria-labelledby=\"label_ff_1_dropdown_4\"><option value=\"\">- Seleccionar -<\/option><option value=\"Si\"  >Yes<\/option><option value=\"No\"  >No<\/option><\/select><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_input_text_7' id='label_ff_1_input_text_7' aria-label=\"Expiration date\">Expiration date<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_7\" class=\"ff-el-form-control\" data-name=\"input_text_7\" id=\"ff_1_input_text_7\"  aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><\/div><div class='ff-el-group ff-text-center ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Enviar\">Enviar<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><div id='fluentform_1_errors' class='ff-errors-in-stack ff_form_instance_1_1 ff-form-loading_errors ff_form_instance_1_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_1_1 = {\"id\":\"1\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_1_1\",\"form_id_selector\":\"fluentform_1\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"Este campo es obligatorio\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"Este campo es obligatorio\"}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"Este campo es obligatorio\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"Este campo es obligatorio\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global\":false,\"global_message\":\"Este campo debe contener un correo electr\\u00f3nico v\\u00e1lido\"}},\"dropdown\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"email_3\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"Este campo es obligatorio\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global\":false,\"global_message\":\"Este campo debe contener un correo electr\\u00f3nico v\\u00e1lido\"}},\"email_4\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"Este campo es obligatorio\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global\":false,\"global_message\":\"Este campo debe contener un correo electr\\u00f3nico v\\u00e1lido\"}},\"subject\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"Este campo es obligatorio\"}},\"input_text\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"dropdown_1\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"dropdown_2\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"input_text_2\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"input_text_1\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"input_text_3\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"input_text_6\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"input_text_5\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"input_text_4\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"dropdown_3\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"checkbox\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"dropdown_4\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}},\"input_text_7\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"Este campo es obligatorio\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n            <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ed6887 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ed6887\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27b6169\" data-id=\"27b6169\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4d1239 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c4d1239\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/davidsinsurance2\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fan Page<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/davidsinsurance2\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">David's Insurance 2<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/DavidsFairburn\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fairburn<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/DavidsRoswell\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Roswell<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/profile.php?id=61550587750015\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Alpharetta<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Horario:Lunes a viernes 10:30 a.m a 7:00 p.m.Sabados 10:30 am a 5:00 p.m Ll\u00e1manos 770 774 8913 Fairburn: 13 Smith [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1325","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/davidsinsurance2.com\/en\/wp-json\/wp\/v2\/pages\/1325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/davidsinsurance2.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/davidsinsurance2.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/davidsinsurance2.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/davidsinsurance2.com\/en\/wp-json\/wp\/v2\/comments?post=1325"}],"version-history":[{"count":22,"href":"https:\/\/davidsinsurance2.com\/en\/wp-json\/wp\/v2\/pages\/1325\/revisions"}],"predecessor-version":[{"id":1457,"href":"https:\/\/davidsinsurance2.com\/en\/wp-json\/wp\/v2\/pages\/1325\/revisions\/1457"}],"wp:attachment":[{"href":"https:\/\/davidsinsurance2.com\/en\/wp-json\/wp\/v2\/media?parent=1325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}